{"id":8952,"date":"2024-08-22T10:50:51","date_gmt":"2024-08-22T10:50:51","guid":{"rendered":"https:\/\/dnccp.gouv.tg\/dnccp\/?p=8952"},"modified":"2024-08-22T10:52:14","modified_gmt":"2024-08-22T10:52:14","slug":"ppm2024-fts","status":"publish","type":"post","link":"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/ppm2024-fts\/","title":{"rendered":"ppm2024 fts"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8952\" class=\"elementor elementor-8952\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c27dcca e-flex e-con-boxed e-con e-parent\" data-id=\"c27dcca\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c125860 e-con-full e-flex e-con e-child\" data-id=\"c125860\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5b2b2f3 e-con-full e-flex e-con e-child\" data-id=\"5b2b2f3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c2e2b0 elementor-grid-eael-col-1 elementor-grid-tablet-eael-col-2 elementor-grid-mobile-eael-col-1 elementor-widget elementor-widget-eael-post-grid\" data-id=\"1c2e2b0\" data-element_type=\"widget\" data-settings=\"{&quot;eael_post_grid_columns&quot;:&quot;eael-col-1&quot;,&quot;eael_post_grid_columns_tablet&quot;:&quot;eael-col-2&quot;,&quot;eael_post_grid_columns_mobile&quot;:&quot;eael-col-1&quot;}\" data-widget_type=\"eael-post-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"eael-post-grid-1c2e2b0\" class=\"eael-post-grid-container\">\n            <div class=\"eael-post-grid eael-post-appender eael-post-appender-1c2e2b0 eael-post-grid-style-one\" data-layout-mode=\"grid\"><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11240\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/arse-3\/\"\n                        title=\"ARSE\">ARSE<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/arse-3\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11238\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/anadeb-2\/\"\n                        title=\"ANADEB\">ANADEB<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/anadeb-2\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11236\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/cagia-2\/\"\n                        title=\"CAGIA\">CAGIA<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/cagia-2\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11234\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/commune-de-binah-1\/\"\n                        title=\"COMMUNE-DE-BINAH-1\">COMMUNE-DE-BINAH-1<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/commune-de-binah-1\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11232\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/commune-de-blitta-2\/\"\n                        title=\"COMMUNE-DE-BLITTA-2\">COMMUNE-DE-BLITTA-2<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/commune-de-blitta-2\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11230\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/compel-5\/\"\n                        title=\"COMPEL\">COMPEL<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/compel-5\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11228\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/commune-de-zio-1\/\"\n                        title=\"COMMUNE-DE-ZIO-1\">COMMUNE-DE-ZIO-1<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/commune-de-zio-1\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11226\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/maedr-daema-2\/\"\n                        title=\"MAEDR-DAEMA\">MAEDR-DAEMA<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/maedr-daema-2\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11224\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/mcacl-ctef\/\"\n                        title=\"MCACL-CTEF\">MCACL-CTEF<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/mcacl-ctef\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11222\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/mesr-ens-at-2\/\"\n                        title=\"MESR-ENS-AT\">MESR-ENS-AT<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/mesr-ens-at-2\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11220\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/mdem-4\/\"\n                        title=\"MDEM\">MDEM<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/mdem-4\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11218\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/mesr-ens-at\/\"\n                        title=\"MESR-ENS-AT\">MESR-ENS-AT<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/mesr-ens-at\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11216\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/mpi-hauqe\/\"\n                        title=\"MPI-HAUQE\">MPI-HAUQE<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/mpi-hauqe\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11214\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/stsl-5\/\"\n                        title=\"STSL\">STSL<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/stsl-5\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11212\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/t-oil-3\/\"\n                        title=\"T-OIL\">T-OIL<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/t-oil-3\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11195\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/anasap-3\/\"\n                        title=\"ANASAP\">ANASAP<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/anasap-3\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11193\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/ange-pqat\/\"\n                        title=\"ANGE-PQAT\">ANGE-PQAT<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/ange-pqat\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11191\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/ccit-2\/\"\n                        title=\"CCIT\">CCIT<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/ccit-2\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11189\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/commune-kpele-2\/\"\n                        title=\"COMMUNE-KPELE-2\">COMMUNE-KPELE-2<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/commune-kpele-2\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"11187\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/cour-des-comptes-3\/\"\n                        title=\"COUR-DES-COMPTES\">COUR-DES-COMPTES<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2024\/ppm-2024-fts\/cour-des-comptes-3\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admins\/\" title=\"Articles par  \" rel=\"author\"> <\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 septembre 2024\">18 septembre 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><\/div>\n            <div class=\"clearfix\"><\/div>\n        <\/div>            <div class=\"eael-load-more-button-wrap\">\n                <button class=\"eael-load-more-button\" id=\"eael-load-more-btn-1c2e2b0\" data-widget-id=\"1c2e2b0\" data-widget=\"1c2e2b0\" data-page-id=\"8952\" data-template=\"{&quot;dir&quot;:&quot;lite&quot;,&quot;file_name&quot;:&quot;default.php&quot;,&quot;name&quot;:&quot;Post-Grid&quot;}\" data-class=\"Essential_Addons_Elementor\\Elements\\Post_Grid\" data-layout=\"grid\" data-page=\"1\" data-args=\"orderby=date&amp;order=desc&amp;ignore_sticky_posts=1&amp;post_status=publish&amp;posts_per_page=20&amp;offset=0&amp;post_type=post&amp;tax_query%5B0%5D%5Btaxonomy%5D=category&amp;tax_query%5B0%5D%5Bfield%5D=term_id&amp;tax_query%5B0%5D%5Bterms%5D%5B0%5D=192&amp;tax_query%5Brelation%5D=AND\" data-max-page=\"17\">\n                    <span class=\"eael-btn-loader button__loader\"><\/span>\n                    <span class=\"eael_load_more_text\">Load More<\/span>\n                <\/button>\n            <\/div>\n            \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ppm2024 fts T\u00e9l\u00e9chargement 22 ao\u00fbt 2024<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"postBodyMargin":[],"postBodyPadding":[],"postBodyBackground":{"backgroundType":"classic","gradient":""},"footnotes":""},"categories":[192],"tags":[],"post_folder":[],"class_list":["post-8952","post","type-post","status-publish","format-standard","hentry","category-ppm-2024-fts"],"_links":{"self":[{"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/posts\/8952"}],"collection":[{"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/comments?post=8952"}],"version-history":[{"count":4,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/posts\/8952\/revisions"}],"predecessor-version":[{"id":8956,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/posts\/8952\/revisions\/8956"}],"wp:attachment":[{"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/media?parent=8952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/categories?post=8952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/tags?post=8952"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/post_folder?post=8952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}