{"id":7986,"date":"2024-07-31T07:39:56","date_gmt":"2024-07-31T07:39:56","guid":{"rendered":"https:\/\/dnccp.gouv.tg\/dnccp\/?p=7986"},"modified":"2024-07-31T16:38:46","modified_gmt":"2024-07-31T16:38:46","slug":"arrete-sur-la-repartition-des-produits-de-vente-des-dao","status":"publish","type":"post","link":"https:\/\/dnccp.gouv.tg\/dnccp\/reglementation\/arretes\/arrete-sur-la-repartition-des-produits-de-vente-des-dao\/","title":{"rendered":"Arr\u00eat\u00e9 n\u00b0068\/MEF\/CAB portant r\u00e9partition des produits issus de la vente des dossiers d&rsquo;appel d&rsquo;offres, entre l&rsquo;Autorit\u00e9 de R\u00e9gulation des March\u00e9s Publics, les organes de passation des march\u00e9s publics des Autorit\u00e9s Contractantes et les b\u00e9n\u00e9ficiaires"},"content":{"rendered":" \n<div id=\"block-4c98c91d-4a92-4de8-b175-8db0f03047ad\" class=\"wp-block-gutenkit-button gkit3047ad gutenkit-block\"><div class=\"gkit-btn-wraper\"><a class=\"gkit-btn\" href=\"https:\/\/dnccp.gouv.tg\/dnccp\/wp-content\/uploads\/2024\/07\/arrete-sur-la-repartition-des-produits-de-vente-des-DAO.pdf\">T\u00e9l\u00e9chargement<div class=\"icon-right\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"gkit-icon\"><path d=\"M288 32c0-17.7-14.3-32-32-32s-32 14.3-32 32V274.7l-73.4-73.4c-12.5-12.5-32.8-12.5-45.3 0s-12.5 32.8 0 45.3l128 128c12.5 12.5 32.8 12.5 45.3 0l128-128c12.5-12.5 12.5-32.8 0-45.3s-32.8-12.5-45.3 0L288 274.7V32zM64 352c-35.3 0-64 28.7-64 64v32c0 35.3 28.7 64 64 64H448c35.3 0 64-28.7 64-64V416c0-35.3-28.7-64-64-64H346.5l-45.3 45.3c-25 25-65.5 25-90.5 0L165.5 352H64zm368 56a24 24 0 1 1 0 48 24 24 0 1 1 0-48z\"\/><\/svg><\/div><\/a><\/div><\/div>\n ","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"postBodyMargin":[],"postBodyPadding":[],"postBodyBackground":{"backgroundType":"classic","gradient":""},"footnotes":""},"categories":[95],"tags":[],"post_folder":[],"class_list":["post-7986","post","type-post","status-publish","format-standard","hentry","category-arretes"],"_links":{"self":[{"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/posts\/7986"}],"collection":[{"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/comments?post=7986"}],"version-history":[{"count":2,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/posts\/7986\/revisions"}],"predecessor-version":[{"id":8224,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/posts\/7986\/revisions\/8224"}],"wp:attachment":[{"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/media?parent=7986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/categories?post=7986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/tags?post=7986"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/post_folder?post=7986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}