{"id":12642,"date":"2026-01-27T12:26:25","date_gmt":"2026-01-27T12:26:25","guid":{"rendered":"https:\/\/dnccp.gouv.tg\/dnccp\/?p=12642"},"modified":"2026-01-27T13:50:35","modified_gmt":"2026-01-27T13:50:35","slug":"ppm2026-fts","status":"publish","type":"post","link":"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/2026\/ppm-2026-fts\/ppm2026-fts\/","title":{"rendered":"ppm2026 fts"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12642\" class=\"elementor elementor-12642\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2096bd8 e-con-full e-flex e-con e-child\" data-id=\"2096bd8\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-423f10f e-con-full e-flex e-con e-child\" data-id=\"423f10f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08cf19c elementor-grid-eael-col-1 elementor-grid-tablet-eael-col-2 elementor-grid-mobile-eael-col-1 elementor-widget elementor-widget-eael-post-grid\" data-id=\"08cf19c\" data-element_type=\"widget\" data-settings=\"{&quot;eael_post_grid_columns&quot;:&quot;eael-col-1&quot;,&quot;eael_post_grid_columns_tablet&quot;:&quot;eael-col-2&quot;,&quot;eael_post_grid_columns_mobile&quot;:&quot;eael-col-1&quot;}\" data-widget_type=\"eael-post-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"eael-post-grid-08cf19c\" class=\"eael-post-grid-container\">\n            <div class=\"eael-post-grid eael-post-appender eael-post-appender-08cf19c eael-post-grid-style-one\" data-layout-mode=\"grid\"><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13427\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/ministere-de-la-sante-de-lhygiene-publique-de-la-couverture-sanitaire-universelle-et-des-assurancesmshpcsua-da\/\"\n                        title=\"Minist\u00e8re de la Sant\u00e9, de l&rsquo;Hygi\u00e8ne Publique, de la Couverture Sanitaire Universelle et des Assurances(MSHPCSUA-DA)\">Minist\u00e8re de la Sant\u00e9, de l&rsquo;Hygi\u00e8ne Publique, de la Couverture Sanitaire Universelle et des<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/ministere-de-la-sante-de-lhygiene-publique-de-la-couverture-sanitaire-universelle-et-des-assurancesmshpcsua-da\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"20 avril 2026\">20 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13424\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-zio-4\/\"\n                        title=\"COMMUNE ZIO 4\">COMMUNE ZIO 4<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-zio-4\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"20 avril 2026\">20 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13422\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-tone-1-5\/\"\n                        title=\"COMMUNE TONE 1\">COMMUNE TONE 1<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-tone-1-5\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"19 avril 2026\">19 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13421\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-ogou-1-2\/\"\n                        title=\"COMMUNE OGOU 1\">COMMUNE OGOU 1<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-ogou-1-2\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"19 avril 2026\">19 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13419\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-haho-4-2\/\"\n                        title=\"COMMUNE HAHO 4\">COMMUNE HAHO 4<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-haho-4-2\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"19 avril 2026\">19 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13417\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-doufelgou-2\/\"\n                        title=\"COMMUNE DOUFELGOU 2\">COMMUNE DOUFELGOU 2<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-doufelgou-2\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"19 avril 2026\">19 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13415\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commission-nationale-des-droits-de-lhommecndh\/\"\n                        title=\"Commission Nationale des Droits de l&rsquo;Homme(CNDH)\">Commission Nationale des Droits de l&rsquo;Homme(CNDH)<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commission-nationale-des-droits-de-lhommecndh\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"19 avril 2026\">19 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13405\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-tchaoudjo-4-2\/\"\n                        title=\"COMMUNE TCHAOUDJO 4\">COMMUNE TCHAOUDJO 4<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-tchaoudjo-4-2\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"19 avril 2026\">19 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13402\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-kpendjal-2-4\/\"\n                        title=\"COMMUNE KPENDJAL 2\">COMMUNE KPENDJAL 2<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-kpendjal-2-4\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"19 avril 2026\">19 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13397\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-blitta-2\/\"\n                        title=\"COMMUNE BLITTA 2\">COMMUNE BLITTA 2<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-blitta-2\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"19 avril 2026\">19 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13394\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/ministere-de-lagriculture-de-la-peche-des-ressources-animales-et-de-la-souverainete-alimentairemaprasa-fsrp\/\"\n                        title=\"Minist\u00e8re de l\u2019Agriculture, de la P\u00eache, des Ressources Animales et de la Souverainet\u00e9 Alimentaire(MAPRASA &#8211; FSRP)\">Minist\u00e8re de l\u2019Agriculture, de la P\u00eache, des Ressources Animales et de la Souverainet\u00e9 Alimentaire(MAPRASA<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/ministere-de-lagriculture-de-la-peche-des-ressources-animales-et-de-la-souverainete-alimentairemaprasa-fsrp\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"19 avril 2026\">19 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13391\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-vo-1-3\/\"\n                        title=\"COMMUNE VO 1\">COMMUNE VO 1<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-vo-1-3\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"19 avril 2026\">19 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13388\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/hapluciarevise-20-02-2026\/\"\n                        title=\"HAPLUCIA(R\u00e9vis\u00e9 20-02-2026)\">HAPLUCIA(R\u00e9vis\u00e9 20-02-2026)<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/hapluciarevise-20-02-2026\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"19 avril 2026\">19 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13386\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/agence-nationale-de-laviation-civileanac\/\"\n                        title=\"Agence Nationale de l&rsquo;Aviation Civile(ANAC)\">Agence Nationale de l&rsquo;Aviation Civile(ANAC)<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/agence-nationale-de-laviation-civileanac\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"19 avril 2026\">19 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13384\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/ministere-de-leducation-nationalemen-revise\/\"\n                        title=\"Minist\u00e8re de l&rsquo;\u00c9ducation Nationale(MEN &#8211; R\u00e9vis\u00e9)\">Minist\u00e8re de l&rsquo;\u00c9ducation Nationale(MEN &#8211; R\u00e9vis\u00e9)<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/ministere-de-leducation-nationalemen-revise\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"19 avril 2026\">19 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13382\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/millennium-challenge-account\/\"\n                        title=\"Millennium Challenge Account\">Millennium Challenge Account<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/millennium-challenge-account\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"19 avril 2026\">19 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13380\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/ministere-de-lagriculture-de-la-peche-des-ressources-animales-et-de-la-souverainete-alimentairemaprasa\/\"\n                        title=\"Minist\u00e8re de l\u2019Agriculture, de la P\u00eache, des Ressources Animales et de la Souverainet\u00e9 Alimentaire(MAPRASA &#8211; DPH)\">Minist\u00e8re de l\u2019Agriculture, de la P\u00eache, des Ressources Animales et de la Souverainet\u00e9 Alimentaire(MAPRASA<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/ministere-de-lagriculture-de-la-peche-des-ressources-animales-et-de-la-souverainete-alimentairemaprasa\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"19 avril 2026\">19 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13378\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/hapluciarevise\/\"\n                        title=\"HAPLUCIA(R\u00e9vis\u00e9)\">HAPLUCIA(R\u00e9vis\u00e9)<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/hapluciarevise\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"19 avril 2026\">19 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13376\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-tone-3-4\/\"\n                        title=\"COMMUNE TONE 3\">COMMUNE TONE 3<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-tone-3-4\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"19 avril 2026\">19 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"13374\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-lacs-2-2\/\"\n                        title=\"COMMUNE LACS 2\">COMMUNE LACS 2<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a\n                            href=\"https:\/\/dnccp.gouv.tg\/dnccp\/passations\/plans-de-passations\/commune-lacs-2-2\/\"\n                            class=\"eael-post-elements-readmore-btn\">T\u00e9l\u00e9chargement<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\"><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"https:\/\/dnccp.gouv.tg\/dnccp\/author\/admin\/\" title=\"Articles par DNCCP TOGO\" rel=\"author\">DNCCP TOGO<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"19 avril 2026\">19 avril 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><\/div>\n            <div class=\"clearfix\"><\/div>\n        <\/div>            <div class=\"eael-load-more-button-wrap\">\n                <button class=\"eael-load-more-button\" id=\"eael-load-more-btn-08cf19c\" data-widget-id=\"08cf19c\" data-widget=\"08cf19c\" data-page-id=\"12642\" data-template=\"{&quot;dir&quot;:&quot;lite&quot;,&quot;file_name&quot;:&quot;default.php&quot;,&quot;name&quot;:&quot;Post-Grid&quot;}\" data-class=\"Essential_Addons_Elementor\\Elements\\Post_Grid\" data-layout=\"grid\" data-page=\"1\" data-args=\"orderby=date&amp;order=desc&amp;ignore_sticky_posts=1&amp;post_status=publish&amp;posts_per_page=20&amp;offset=0&amp;post_type=post&amp;tax_query%5B0%5D%5Btaxonomy%5D=category&amp;tax_query%5B0%5D%5Bfield%5D=term_id&amp;tax_query%5B0%5D%5Bterms%5D%5B0%5D=324&amp;tax_query%5Brelation%5D=AND\" data-max-page=\"9\">\n                    <span class=\"eael-btn-loader button__loader\"><\/span>\n                    <span class=\"eael_load_more_text\">Load More<\/span>\n                <\/button>\n            <\/div>\n            \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ppm2026 fts T\u00e9l\u00e9chargement DNCCP TOGO27 janvier 2026 Minist\u00e8re de l\u2019Economie Maritime et de la Protection C\u00f4ti\u00e8re T\u00e9l\u00e9chargement DNCCP TOGO16 janvier<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"postBodyMargin":[],"postBodyPadding":[],"postBodyBackground":{"backgroundType":"classic","gradient":""},"footnotes":""},"categories":[324],"tags":[],"post_folder":[],"class_list":["post-12642","post","type-post","status-publish","format-standard","hentry","category-ppm-2026-fts"],"_links":{"self":[{"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/posts\/12642"}],"collection":[{"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/comments?post=12642"}],"version-history":[{"count":4,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/posts\/12642\/revisions"}],"predecessor-version":[{"id":12653,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/posts\/12642\/revisions\/12653"}],"wp:attachment":[{"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/media?parent=12642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/categories?post=12642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/tags?post=12642"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/dnccp.gouv.tg\/dnccp\/wp-json\/wp\/v2\/post_folder?post=12642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}